{"id":171,"count":5,"description":"","link":"https:\/\/travelwithkids.net\/en\/category\/belgium\/","name":"Belgium","slug":"belgium","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Belgium Archieven - travelwithkids.net<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Belgium Archieven - travelwithkids.net\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travelwithkids.net\/en\/category\/belgium\/\" \/>\n<meta property=\"og:site_name\" content=\"travelwithkids.net\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/travelwithkids.net\\\/en\\\/category\\\/belgium\\\/\",\"url\":\"https:\\\/\\\/travelwithkids.net\\\/en\\\/category\\\/belgium\\\/\",\"name\":\"Belgium Archieven - travelwithkids.net\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/travelwithkids.net\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/travelwithkids.net\\\/en\\\/category\\\/belgium\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/travelwithkids.net\\\/en\\\/category\\\/belgium\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/travelwithkids.net\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Belgium\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/travelwithkids.net\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/travelwithkids.net\\\/en\\\/\",\"name\":\"travelwithkids.net\",\"description\":\"Tips en inspiratie voor reizen met kids\",\"publisher\":{\"@id\":\"https:\\\/\\\/travelwithkids.net\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/travelwithkids.net\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/travelwithkids.net\\\/en\\\/#organization\",\"name\":\"opreismetkids.com\",\"url\":\"https:\\\/\\\/travelwithkids.net\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/travelwithkids.net\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/travelwithkids.net\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cropped-LOGO-opreismetkids-2.png\",\"contentUrl\":\"https:\\\/\\\/travelwithkids.net\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cropped-LOGO-opreismetkids-2.png\",\"width\":200,\"height\":78,\"caption\":\"opreismetkids.com\"},\"image\":{\"@id\":\"https:\\\/\\\/travelwithkids.net\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/opreismet.kids\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Belgium Archieven - travelwithkids.net","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Belgium Archieven - travelwithkids.net","og_url":"https:\/\/travelwithkids.net\/en\/category\/belgium\/","og_site_name":"travelwithkids.net","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/travelwithkids.net\/en\/category\/belgium\/","url":"https:\/\/travelwithkids.net\/en\/category\/belgium\/","name":"Belgium Archieven - travelwithkids.net","isPartOf":{"@id":"https:\/\/travelwithkids.net\/en\/#website"},"breadcrumb":{"@id":"https:\/\/travelwithkids.net\/en\/category\/belgium\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/travelwithkids.net\/en\/category\/belgium\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/travelwithkids.net\/en\/"},{"@type":"ListItem","position":2,"name":"Belgium"}]},{"@type":"WebSite","@id":"https:\/\/travelwithkids.net\/en\/#website","url":"https:\/\/travelwithkids.net\/en\/","name":"travelwithkids.net","description":"Tips en inspiratie voor reizen met kids","publisher":{"@id":"https:\/\/travelwithkids.net\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travelwithkids.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/travelwithkids.net\/en\/#organization","name":"opreismetkids.com","url":"https:\/\/travelwithkids.net\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/travelwithkids.net\/en\/#\/schema\/logo\/image\/","url":"https:\/\/travelwithkids.net\/wp-content\/uploads\/2022\/01\/cropped-LOGO-opreismetkids-2.png","contentUrl":"https:\/\/travelwithkids.net\/wp-content\/uploads\/2022\/01\/cropped-LOGO-opreismetkids-2.png","width":200,"height":78,"caption":"opreismetkids.com"},"image":{"@id":"https:\/\/travelwithkids.net\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/opreismet.kids\/"]}]}},"_links":{"self":[{"href":"https:\/\/travelwithkids.net\/en\/wp-json\/wp\/v2\/categories\/171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travelwithkids.net\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/travelwithkids.net\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/travelwithkids.net\/en\/wp-json\/wp\/v2\/posts?categories=171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}